{"id":313,"date":"2025-12-08T21:04:02","date_gmt":"2025-12-08T21:04:02","guid":{"rendered":"https:\/\/lesna.al\/?page_id=313"},"modified":"2026-02-05T09:10:45","modified_gmt":"2026-02-05T09:10:45","slug":"sherbimet","status":"publish","type":"page","link":"https:\/\/lesna.al\/al\/sherbimet\/","title":{"rendered":"Sh\u00ebrbimet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"313\" class=\"elementor elementor-313\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-671ff057 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"671ff057\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3aa10718\" data-id=\"3aa10718\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52daa28c elementor-widget elementor-widget-heading\" data-id=\"52daa28c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sh\u00ebrbimet Tona<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a553596 elementor-icon-list--layout-inline elementor-align-center elementor-widget__width-auto elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4a553596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sh\u00ebrbimet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd6120e elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd6120e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-954cd46\" data-id=\"954cd46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c2124a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3c2124a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sh\u00ebrbimet Tona<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0d1b2 elementor-widget elementor-widget-heading\" data-id=\"3f0d1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prodhim, Shitje dhe Montim!<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1855064 e-flex e-con-boxed e-con e-parent\" data-id=\"1855064\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9aef05b elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9aef05b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Dyer\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-door-open-solid\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tDyer\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLESNA ofron nj\u00eb gam\u00eb t\u00eb gjer\u00eb dyresh p\u00ebr \u00e7do ambient. Nga dyert e brendshme dhe t\u00eb jashtme, te dyert hyr\u00ebse t\u00eb blinduara dhe dyert e garazhit, \u00e7do produkt \u00ebsht\u00eb i prodhuar me materiale cil\u00ebsore dhe standarde evropiane.\nSiguri, funksionalitet dhe dizajn i p\u00ebrkryer.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4802f8c e-flex e-con-boxed e-con e-parent\" data-id=\"4802f8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ebff55 elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3ebff55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Dritare\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-window-light\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tDritare\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDritare cil\u00ebsore, t\u00eb q\u00ebndrueshme dhe t\u00eb dizajnuara p\u00ebr efikasitDritaret e LESNA jan\u00eb t\u00eb q\u00ebndrueshme, energjetikisht efikase dhe estetike. Ofrojm\u00eb dritare druri dhe PVC, dritare termike dhe p\u00ebr \u00e7ati, t\u00eb cilat sigurojn\u00eb izolim t\u00eb lart\u00eb, funksionalitet maksimal dhe dizajn modern.\nDritare q\u00eb ndri\u00e7ojn\u00eb ambientin dhe ruajn\u00eb rehati.et energjetik dhe bukuri estetike.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-822bd3e e-flex e-con-boxed e-con e-parent\" data-id=\"822bd3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb2981c elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"eb2981c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Mobilje\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-window-maximize\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tMobilje\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKrijojm\u00eb mobilje funksionale dhe estetike p\u00ebr \u00e7do hap\u00ebsir\u00eb. Nga kuzhinat dhe dhomat e gjumit, te mobiljet p\u00ebr zyra dhe tavolina ngr\u00ebnieje, \u00e7do produkt \u00ebsht\u00eb i personalizuar sipas nevojave tuaja dhe prodhuar me materiale cil\u00ebsore p\u00ebr q\u00ebndrueshm\u00ebri dhe stil.\nMobilje q\u00eb kombinon dizajn modern, komoditet dhe funksionalitet.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-742d248\" data-id=\"742d248\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bef2c17 elementor-widget elementor-widget-text-editor\" data-id=\"bef2c17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>N\u00eb LESNA ofrojm\u00eb nj\u00eb zgjidhje t\u00eb plot\u00eb, nga prodhimi deri te montimi final. \u00c7do produkt realizohet n\u00eb fabrikat tona me teknologji moderne dhe standarde t\u00eb larta cil\u00ebsie, duke garantuar q\u00eb dyert, dritaret dhe mobiljet tuaja t\u00eb jen\u00eb t\u00eb q\u00ebndrueshme dhe t\u00eb p\u00ebrshtatura p\u00ebr \u00e7do ambient.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a71170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a71170\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2bfc60e\" data-id=\"2bfc60e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e06999c elementor-widget elementor-widget-spacer\" data-id=\"e06999c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-214f0bd elementor-widget elementor-widget-heading\" data-id=\"214f0bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Na Kontaktoni N\u00ebse Keni Pyetje Rreth Sh\u00ebrbimeve Tona.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6445894 elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6445894\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Instalime t\u00eb Shpejta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Matje Falas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d254bd2 elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d254bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">10+ Vite Garanci<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Design Modern<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d0480 elementor-view-framed elementor-position-inline-start elementor-shape-square elementor-widget__width-auto elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b6d0480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Kontakt\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tKontakt\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t+355 67 200 3356\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7213ca10 elementor-section-full_width elementor-section-content-middle elementor-section-height-default elementor-section-height-default\" data-id=\"7213ca10\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7b3e6287 elementor-hidden-phone\" data-id=\"7b3e6287\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:997,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/25.jpg&quot;},{&quot;id&quot;:1008,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/36.jpg&quot;},{&quot;id&quot;:1010,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/40.jpg&quot;},{&quot;id&quot;:1001,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/29.jpg&quot;},{&quot;id&quot;:995,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/23.jpg&quot;},{&quot;id&quot;:993,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/20.jpg&quot;},{&quot;id&quot;:986,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13.jpg&quot;},{&quot;id&quot;:990,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/17.jpg&quot;},{&quot;id&quot;:992,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/19.jpg&quot;},{&quot;id&quot;:983,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/10.jpg&quot;},{&quot;id&quot;:982,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/9.jpg&quot;},{&quot;id&quot;:981,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/8.jpg&quot;},{&quot;id&quot;:980,&quot;url&quot;:&quot;https:\\\/\\\/lesna.al\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:2600,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e5e0c12 elementor-widget elementor-widget-spacer\" data-id=\"1e5e0c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79a57368\" data-id=\"79a57368\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e3f75e9 elementor-widget elementor-widget-heading\" data-id=\"2e3f75e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">LESNA ALBANIA<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3366cf75 elementor-widget elementor-widget-heading\" data-id=\"3366cf75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kualitet &amp; Profesionaliz\u00ebm<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efb7999 elementor-widget elementor-widget-text-editor\" data-id=\"efb7999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"143\" data-end=\"417\">N\u00eb LESNA, \u00e7do produkt dhe sh\u00ebrbim realizohet me standarde t\u00eb larta kualiteti dhe profesionalizmi. Materialet premium, teknologjia moderne dhe stafi i trajnuar sigurojn\u00eb q\u00eb dyert, dritaret dhe mobiljet tuaja t\u00eb jen\u00eb t\u00eb q\u00ebndrueshme, funksionale dhe estetikisht t\u00eb p\u00ebrkryera.<\/p><p data-start=\"419\" data-end=\"473\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"419\" data-end=\"473\" data-is-last-node=\"\">Kualitet q\u00eb ndihmon, profesionaliz\u00ebm q\u00eb ju besoni.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b1a740a elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"1b1a740a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"jki jki-phone-call-line\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3117574 elementor-widget elementor-widget-text-editor\" data-id=\"3117574\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #ffff00;\"><a style=\"color:#f6e80d;\" href=\"tel:+355672003356\" target=\"_blank\" rel=\"noopener\"><strong>+355 67 200 3356<\/strong><\/a><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32a086d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32a086d6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-479179e6\" data-id=\"479179e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f67ced2 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1f67ced2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">PROCESI<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46c8b60a elementor-widget elementor-widget-heading\" data-id=\"46c8b60a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Si Ta Realizoni Projektin Tuaj me LESNA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66a04715 elementor-widget elementor-widget-text-editor\" data-id=\"66a04715\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Filloni duke rezervuar nj\u00eb takim me ekipin ton\u00eb p\u00ebr k\u00ebshillim dhe ofert\u00eb t\u00eb personalizuar. M\u00eb pas, produkti juaj prodhohet me materiale cil\u00ebsore dhe standarde t\u00eb larta. Pas p\u00ebrfundimit, dor\u00ebzohet i sigurt n\u00eb adres\u00ebn tuaj dhe instalohet profesionalisht, duke ju mund\u00ebsuar t\u00eb shijoni ambientin e p\u00ebrmir\u00ebsuar menj\u00ebher\u00eb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3423f68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3423f68\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3a663b1a\" data-id=\"3a663b1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7617c695 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"7617c695\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"675\" height=\"90\" src=\"https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow.png\" class=\"attachment-full size-full wp-image-32\" alt=\"\" srcset=\"https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow.png 675w, https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow-600x80.png 600w, https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow-300x40.png 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9b00a5 elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c9b00a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Rezervoni Takimin\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-smartphone2-light\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tRezervoni Takimin\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRezervoni nj\u00eb takim me ekipin ton\u00eb p\u00ebr k\u00ebshillim dhe ofert\u00eb t\u00eb personalizuar.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4d637d78\" data-id=\"4d637d78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-743748a9 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"743748a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"675\" height=\"90\" src=\"https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow.png\" class=\"attachment-full size-full wp-image-32\" alt=\"\" srcset=\"https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow.png 675w, https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow-600x80.png 600w, https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow-300x40.png 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c73e4ed elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c73e4ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Prodhim\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-window-light\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tProdhim\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tProduktet tuaja prodhohen sipas k\u00ebrkes\u00ebs q\u00eb keni dhe matjeve t\u00eb kryera nga stafi.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2b91e740\" data-id=\"2b91e740\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6cc557 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3a6cc557\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"675\" height=\"90\" src=\"https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow.png\" class=\"attachment-full size-full wp-image-32\" alt=\"\" srcset=\"https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow.png 675w, https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow-600x80.png 600w, https:\/\/lesna.al\/wp-content\/uploads\/2025\/12\/arrow-300x40.png 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cae9e3 elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4cae9e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Dor\u00ebzimi tek Ju\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-Safe-house-light\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tDor\u00ebzimi tek Ju\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDor\u00ebzim i shpejt\u00eb dhe i sigurt n\u00eb adres\u00ebn tuaj, kudo q\u00eb ndodheni, brenda dhe jasht\u00eb Shqip\u00ebris,\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-679403fe\" data-id=\"679403fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14a4c0b elementor-view-framed elementor-shape-square elementor-widget__width-auto elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"14a4c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Montim\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"jki jki-customer-support-light\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"tel:+355672003356\" target=\"_blank\" >\n\t\t\t\t\t\t\tMontim\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMontim profesional dhe komoditet i menj\u00ebhersh\u00ebm, p\u00ebr t\u00eb shijuar ambientin tuj me produkte t\u00eb kuletitetit premium.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sh\u00ebrbimet Tona Home Sh\u00ebrbimet Sh\u00ebrbimet Tona Prodhim, Shitje dhe Montim! Dyer LESNA ofron nj\u00eb gam\u00eb t\u00eb gjer\u00eb dyresh p\u00ebr \u00e7do ambient. Nga dyert e brendshme dhe t\u00eb jashtme, te dyert hyr\u00ebse t\u00eb blinduara dhe dyert e garazhit, \u00e7do produkt \u00ebsht\u00eb i prodhuar me materiale cil\u00ebsore dhe standarde evropiane. Siguri, funksionalitet dhe dizajn i p\u00ebrkryer. Dritare [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-313","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/pages\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":0,"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/pages\/313\/revisions"}],"wp:attachment":[{"href":"https:\/\/lesna.al\/al\/wp-json\/wp\/v2\/media?parent=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}